{"id":11946,"date":"2023-08-01T11:24:26","date_gmt":"2023-08-01T09:24:26","guid":{"rendered":"https:\/\/www.leatcon.com\/?p=11946"},"modified":"2023-09-01T15:25:04","modified_gmt":"2023-09-01T13:25:04","slug":"moritz-enders-silbermond","status":"publish","type":"post","link":"https:\/\/www.leatcon.com\/en\/studioszene-en\/moritz-enders-silbermond\/","title":{"rendered":"Analoges vs. digitales Mixing"},"content":{"rendered":"<figure><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-5158\" src=\"https:\/\/www.studioszene.de\/app\/uploads\/2023\/06\/SZ23-Speaker-Moritz-Enders_1200x628-1024x536.jpg\" alt=\"\" width=\"1024\" height=\"536\" \/><\/figure>\n<p style=\"font-weight: 400;\">Moritz Enders ist ein erfolgreicher Toningenieur und Produzent, der mit namhaften K\u00fcnstlern wie Silbermond, Casper oder The Intersphere zusammengearbeitet und mit ihnen Alben produzierte, die in den Charts erfolgreich waren.<\/p>\n<p><strong>Masterclass mit Moritz Enders auf der Studioszene 2023:<\/strong><\/p>\n<p>Wann: 18.10.2023<br \/>\nUhrzeit: 14:00 &#8211; 16:30 Uhr<br \/>\nB\u00fchne: Masterclass<\/p>\n<p class=\"align-center\"><a href=\"https:\/\/tickets.leatcon.com\/de\/public\/studioszene?utm_source=Website&#038;utm_medium=Blogpost&#038;utm_campaign=Early+Bird+Ticket&#038;utm_id=Studioszene\" target=\"_blank\" rel=\"noopener\"><span class=\"bold\"><a class=\"dm-button button class-button-two\" href=\"https:\/\/tickets.leatcon.com\/de\/public\/studioszene?utm_source=Website&utm_medium=Blogpost&utm_campaign=Early+Bird+Ticket&utm_id=Studioszene\" alt=\"Get Your Ticket!\" target=\"_blank\">Get Your Ticket!<\/a><br \/>\n<\/span><\/a><\/p>\n<h3 class=\"style-scope ytd-watch-metadata\">Pro Tools @ Work: Moritz Enders (Bosse, Silbermond, Casper u.a.)<\/h3>\n<div class=\"videoWrapper flex-video widescreen\">\n<div class=\"videoWrapper flex-video widescreen\"><iframe loading=\"lazy\" title=\"Pro Tools @ Work: Moritz Enders (Bosse, Silbermond, Casper u.a.) I Avid Pro Tools I Musikproduktion\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/B6uFRlSg0B0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Moritz Enders ist ein erfolgreicher Toningenieur und Produzent, der mit namhaften K\u00fcnstlern wie Silbermond, Casper oder The Intersphere zusammengearbeitet und mit ihnen Alben produzierte, die in den Charts erfolgreich waren&#8230;.<\/p>\n","protected":false},"author":24,"featured_media":11834,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[162],"tags":[],"coauthors":[160],"class_list":["post-11946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-studioszene-en"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Analoges vs. digitales Mixing - LEaT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Analoges vs. digitales Mixing - LEaT\" \/>\n<meta property=\"og:description\" content=\"Moritz Enders ist ein erfolgreicher Toningenieur und Produzent, der mit namhaften K\u00fcnstlern wie Silbermond, Casper oder The Intersphere zusammengearbeitet und mit ihnen Alben produzierte, die in den Charts erfolgreich waren....\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/\" \/>\n<meta property=\"og:site_name\" content=\"LEaT\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-01T09:24:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-01T13:25:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.leatcon.com\/app\/uploads\/2023\/07\/SZ23-Speaker-Moritz-Enders_880x540.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marc Bohn\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marc Bohn\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.leatcon.com\/en\/studioszene-en\/moritz-enders-silbermond\/\",\"url\":\"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/\",\"name\":\"Analoges vs. digitales Mixing - LEaT\",\"isPartOf\":{\"@id\":\"https:\/\/www.leatcon.com\/#website\"},\"datePublished\":\"2023-08-01T09:24:26+00:00\",\"dateModified\":\"2023-09-01T13:25:04+00:00\",\"author\":{\"@id\":\"https:\/\/www.leatcon.com\/#\/schema\/person\/d1a5d0c34ced601ba07ad22924d70ddc\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.leatcon.com\/en\/leat-con-26\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Analoges vs. digitales Mixing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.leatcon.com\/#website\",\"url\":\"https:\/\/www.leatcon.com\/\",\"name\":\"LEaT\",\"description\":\"Live, Entertainment and Technology\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.leatcon.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.leatcon.com\/#\/schema\/person\/d1a5d0c34ced601ba07ad22924d70ddc\",\"name\":\"Marc Bohn\",\"url\":\"https:\/\/www.leatcon.com\/en\/author\/marc-bohn\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Analoges vs. digitales Mixing - LEaT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/","og_locale":"en_US","og_type":"article","og_title":"Analoges vs. digitales Mixing - LEaT","og_description":"Moritz Enders ist ein erfolgreicher Toningenieur und Produzent, der mit namhaften K\u00fcnstlern wie Silbermond, Casper oder The Intersphere zusammengearbeitet und mit ihnen Alben produzierte, die in den Charts erfolgreich waren....","og_url":"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/","og_site_name":"LEaT","article_published_time":"2023-08-01T09:24:26+00:00","article_modified_time":"2023-09-01T13:25:04+00:00","og_image":[{"width":880,"height":540,"url":"https:\/\/www.leatcon.com\/app\/uploads\/2023\/07\/SZ23-Speaker-Moritz-Enders_880x540.jpg","type":"image\/jpeg"}],"author":"Marc Bohn","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Marc Bohn"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leatcon.com\/en\/studioszene-en\/moritz-enders-silbermond\/","url":"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/","name":"Analoges vs. digitales Mixing - LEaT","isPartOf":{"@id":"https:\/\/www.leatcon.com\/#website"},"datePublished":"2023-08-01T09:24:26+00:00","dateModified":"2023-09-01T13:25:04+00:00","author":{"@id":"https:\/\/www.leatcon.com\/#\/schema\/person\/d1a5d0c34ced601ba07ad22924d70ddc"},"breadcrumb":{"@id":"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.studioszene.de\/allgemein\/moritz-enders-silbermond\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.leatcon.com\/en\/leat-con-26\/"},{"@type":"ListItem","position":2,"name":"Analoges vs. digitales Mixing"}]},{"@type":"WebSite","@id":"https:\/\/www.leatcon.com\/#website","url":"https:\/\/www.leatcon.com\/","name":"LEaT","description":"Live, Entertainment and Technology","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leatcon.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.leatcon.com\/#\/schema\/person\/d1a5d0c34ced601ba07ad22924d70ddc","name":"Marc Bohn","url":"https:\/\/www.leatcon.com\/en\/author\/marc-bohn\/"}]}},"_links":{"self":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/posts\/11946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/comments?post=11946"}],"version-history":[{"count":3,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/posts\/11946\/revisions"}],"predecessor-version":[{"id":12795,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/posts\/11946\/revisions\/12795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/media\/11834"}],"wp:attachment":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/media?parent=11946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/categories?post=11946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/tags?post=11946"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/coauthors?post=11946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}