{"id":22078,"date":"2026-02-03T12:00:14","date_gmt":"2026-02-03T11:00:14","guid":{"rendered":"https:\/\/www.leatcon.com\/?post_type=mp-event&#038;p=22078"},"modified":"2026-02-09T11:10:31","modified_gmt":"2026-02-09T10:10:31","slug":"cheers-to-5-years-2","status":"publish","type":"mp-event","link":"https:\/\/www.leatcon.com\/en\/timetable\/event\/cheers-to-5-years-2\/","title":{"rendered":"Cheers to 5 Years"},"content":{"rendered":"<p>What, wir werden schon 5? Na, wenn das kein Grund zum Feiern ist! Komm vorbei und sto\u00df mit uns auf die gemeinsamen Jahre an &#8211; Sekt &amp; Kuchen geht auf uns!<\/p>\n<p>Ort: Networking Area untere Ebene<\/p>\n<p><span class=\"bold\">Let&#8217;s celebrate 5 years \u2013 and make the next 5 even better. \ud83c\udf89<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>What, wir werden schon 5? Na, wenn das kein Grund zum Feiern ist! Komm vorbei und sto\u00df mit uns auf die gemeinsamen Jahre an &#8211; Sekt &amp; Kuchen geht auf&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","mp-event_category":[244],"mp-event_tag":[245],"coauthors":[19],"class_list":["post-22078","mp-event","type-mp-event","status-publish","hentry","mp-event_category-5-maerz-2026","mp-event_tag-leat-x","mp-event-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cheers to 5 Years - LEaT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cheers to 5 Years - LEaT\" \/>\n<meta property=\"og:description\" content=\"What, wir werden schon 5? Na, wenn das kein Grund zum Feiern ist! Komm vorbei und sto\u00df mit uns auf die gemeinsamen Jahre an &#8211; Sekt &amp; Kuchen geht auf...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/\" \/>\n<meta property=\"og:site_name\" content=\"LEaT\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-09T10:10:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Redaktion\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/\",\"url\":\"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/\",\"name\":\"Cheers to 5 Years - LEaT\",\"isPartOf\":{\"@id\":\"https:\/\/www.leatcon.com\/#website\"},\"datePublished\":\"2026-02-03T11:00:14+00:00\",\"dateModified\":\"2026-02-09T10:10:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.leatcon.com\/en\/leat-con-26\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/www.leatcon.com\/timetable\/event\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cheers to 5 Years\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.leatcon.com\/#website\",\"url\":\"https:\/\/www.leatcon.com\/\",\"name\":\"LEaT\",\"description\":\"Live, Entertainment and Technology\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.leatcon.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cheers to 5 Years - LEaT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/","og_locale":"en_US","og_type":"article","og_title":"Cheers to 5 Years - LEaT","og_description":"What, wir werden schon 5? Na, wenn das kein Grund zum Feiern ist! Komm vorbei und sto\u00df mit uns auf die gemeinsamen Jahre an &#8211; Sekt &amp; Kuchen geht auf...","og_url":"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/","og_site_name":"LEaT","article_modified_time":"2026-02-09T10:10:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute","Written by":"Redaktion"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/","url":"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/","name":"Cheers to 5 Years - LEaT","isPartOf":{"@id":"https:\/\/www.leatcon.com\/#website"},"datePublished":"2026-02-03T11:00:14+00:00","dateModified":"2026-02-09T10:10:31+00:00","breadcrumb":{"@id":"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.leatcon.com\/timetable\/event\/cheers-to-5-years-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.leatcon.com\/en\/leat-con-26\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.leatcon.com\/timetable\/event\/"},{"@type":"ListItem","position":3,"name":"Cheers to 5 Years"}]},{"@type":"WebSite","@id":"https:\/\/www.leatcon.com\/#website","url":"https:\/\/www.leatcon.com\/","name":"LEaT","description":"Live, Entertainment and Technology","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leatcon.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/mp-event\/22078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/mp-event"}],"about":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/types\/mp-event"}],"author":[{"embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/comments?post=22078"}],"wp:attachment":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/media?parent=22078"}],"wp:term":[{"taxonomy":"mp-event_category","embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/mp-event_category?post=22078"},{"taxonomy":"mp-event_tag","embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/mp-event_tag?post=22078"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/coauthors?post=22078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}