{"id":17211,"date":"2024-08-29T17:11:17","date_gmt":"2024-08-29T15:11:17","guid":{"rendered":"https:\/\/www.leatcon.com\/?post_type=mp-event&#038;p=17211"},"modified":"2024-10-21T21:44:36","modified_gmt":"2024-10-21T19:44:36","slug":"port-des-lumieres-immersive-kunstausstellung","status":"publish","type":"mp-event","link":"https:\/\/www.leatcon.com\/en\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/","title":{"rendered":"(AUSGEBUCHT) Port des Lumi\u00e8res | Immersive Kunstausstellung"},"content":{"rendered":"<p>V\u00f6lliges Eintauchen in die faszinierende Welt der immersiven Kunst! Das ist es, was Culturespaces nun auch in Hamburg erm\u00f6glichen m\u00f6chte und plant daf\u00fcr das erste dauerhafte Zentrum f\u00fcr immersive Kunst: Port des Lumi\u00e8res im neuen Westfield Hamburg \u00dcberseequartier in der HafenCity. Hier entsteht ein atemberaubendes visuelles Erlebnis mit modernster Technologie: 80 Projektoren und eine riesige Projektionsfl\u00e4che von 3.200 qm auf 1.700 qm Ausstellungsfl\u00e4che sollen Kunst zu einem unvergesslichen Erlebnis f\u00fcr alle Sinne machen.<\/p>\n<p>Als Teilnehmer unseres Tech Trips genie\u00dft du exklusive Vorteile: Du bist Teil einer kleinen Gruppe, die einen exklusiven Blick hinter die Kulissen bekommt! Zu Beginn wirst du pers\u00f6nlich von Jan-Peter Becker, General Manager des Port des Lumi\u00e8res, begr\u00fc\u00dft und in die Ausstellungsfl\u00e4che eingeladen. Freu dich auf ein exklusives Vorabgespr\u00e4ch mit spannenden Insights und eine gef\u00fchrte Tour durch die beeindruckenden Ausstellungsr\u00e4ume \u2013 eine einzigartige Gelegenheit, spannende Einblicke in den Entstehungsprozess und die innovativen technischen Details dieser au\u00dfergew\u00f6hnlichen Kunstausstellung zu erhalten und all deine Fragen zu stellen.<\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" class=\"content-img alignnone wp-image-17308\" src=\"https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-1024x683.jpg\" alt=\"Port des Lumi\u00e8res (Immersive Kunstausstellung) im Rahmen der LEaT con 24\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-1024x683.jpg 1024w, https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-300x200.jpg 300w, https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-768x512.jpg 768w, https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-1536x1024.jpg 1536w, https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-150x100.jpg 150w, https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-565x377.jpg 565w, https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-1500x1000.jpg 1500w, https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-1150x767.jpg 1150w, https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-640x427.jpg 640w, https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web-600x400.jpg 600w, https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web.jpg 2046w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<p>&#8212;<\/p>\n<p><span class=\"bold\">Wann?<\/span><br \/>\nMittwoch, 23. Oktober 2024, 09:00-11:00 Uhr<\/p>\n<p><span class=\"bold\">Anmeldung:<\/span><br \/>\nBitte beachte vor deiner Anmeldung, dass dieses Angebot nicht auf dem Messegel\u00e4nde, sondern extern beim jeweiligen Anbieter stattfindet.<br \/>\nDieses Angebot gilt nur f\u00fcr Inhaber eines INSIGHTS Tickets.<\/p>\n<figure><a href=\"http:\/\/tickets.leatcon.com\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"content-img alignnone wp-image-13327\" src=\"https:\/\/www.leatcon.com\/app\/uploads\/2023\/09\/Jetzt-Ticket-sichern-Button-580x141-1.png\" alt=\"Jetzt-Ticket-sichern\" width=\"200\" height=\"49\" srcset=\"https:\/\/www.leatcon.com\/app\/uploads\/2023\/09\/Jetzt-Ticket-sichern-Button-580x141-1.png 580w, https:\/\/www.leatcon.com\/app\/uploads\/2023\/09\/Jetzt-Ticket-sichern-Button-580x141-1-300x73.png 300w, https:\/\/www.leatcon.com\/app\/uploads\/2023\/09\/Jetzt-Ticket-sichern-Button-580x141-1-150x36.png 150w, https:\/\/www.leatcon.com\/app\/uploads\/2023\/09\/Jetzt-Ticket-sichern-Button-580x141-1-565x137.png 565w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/figure>\n<hr \/>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als Teilnehmer des Tech Trips genie\u00dft du exklusive Vorteile: Sei Teil einer der ersten Gruppen, die die neu er\u00f6ffneten Ausstellungen \u201eGustav Klimt \u2013 Gold und Farbe\u201c sowie \u201eHundertwasser \u2013 auf den Spuren der Wiener Secession\u201c besuchen d\u00fcrfen! Noch vor der offiziellen \u00d6ffnungszeit wirst du pers\u00f6nlich von Jan-Peter Becker, General Manager des Port des Lumi\u00e8res, begr\u00fc\u00dft und in die noch geschlossene Ausstellung eingeladen.<\/p>\n","protected":false},"author":11,"featured_media":17308,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","mp-event_category":[207],"mp-event_tag":[231,211,209],"coauthors":[30],"class_list":["post-17211","mp-event","type-mp-event","status-publish","has-post-thumbnail","hentry","mp-event_category-23-10-2024","mp-event_tag-av","mp-event_tag-avcon","mp-event_tag-leat-con","mp-event-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>(AUSGEBUCHT) Port des Lumi\u00e8res | Immersive Kunstausstellung - LEaT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(AUSGEBUCHT) Port des Lumi\u00e8res | Immersive Kunstausstellung - LEaT\" \/>\n<meta property=\"og:description\" content=\"Als Teilnehmer des Tech Trips genie\u00dft du exklusive Vorteile: Sei Teil einer der ersten Gruppen, die die neu er\u00f6ffneten Ausstellungen \u201eGustav Klimt \u2013 Gold und Farbe\u201c sowie \u201eHundertwasser \u2013 auf den Spuren der Wiener Secession\u201c besuchen d\u00fcrfen! Noch vor der offiziellen \u00d6ffnungszeit wirst du pers\u00f6nlich von Jan-Peter Becker, General Manager des Port des Lumi\u00e8res, begr\u00fc\u00dft und in die noch geschlossene Ausstellung eingeladen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/\" \/>\n<meta property=\"og:site_name\" content=\"LEaT\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-21T19:44:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2046\" \/>\n\t<meta property=\"og:image:height\" content=\"1364\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Lena\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/\",\"url\":\"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/\",\"name\":\"(AUSGEBUCHT) Port des Lumi\u00e8res | Immersive Kunstausstellung - LEaT\",\"isPartOf\":{\"@id\":\"https:\/\/www.leatcon.com\/#website\"},\"datePublished\":\"2024-08-29T15:11:17+00:00\",\"dateModified\":\"2024-10-21T19:44:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.leatcon.com\/en\/leat-con-26\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\/\/www.leatcon.com\/timetable\/event\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"(AUSGEBUCHT) Port des Lumi\u00e8res | Immersive Kunstausstellung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.leatcon.com\/#website\",\"url\":\"https:\/\/www.leatcon.com\/\",\"name\":\"LEaT\",\"description\":\"Live, Entertainment and Technology\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.leatcon.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(AUSGEBUCHT) Port des Lumi\u00e8res | Immersive Kunstausstellung - LEaT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/","og_locale":"en_US","og_type":"article","og_title":"(AUSGEBUCHT) Port des Lumi\u00e8res | Immersive Kunstausstellung - LEaT","og_description":"Als Teilnehmer des Tech Trips genie\u00dft du exklusive Vorteile: Sei Teil einer der ersten Gruppen, die die neu er\u00f6ffneten Ausstellungen \u201eGustav Klimt \u2013 Gold und Farbe\u201c sowie \u201eHundertwasser \u2013 auf den Spuren der Wiener Secession\u201c besuchen d\u00fcrfen! Noch vor der offiziellen \u00d6ffnungszeit wirst du pers\u00f6nlich von Jan-Peter Becker, General Manager des Port des Lumi\u00e8res, begr\u00fc\u00dft und in die noch geschlossene Ausstellung eingeladen.","og_url":"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/","og_site_name":"LEaT","article_modified_time":"2024-10-21T19:44:36+00:00","og_image":[{"width":2046,"height":1364,"url":"https:\/\/www.leatcon.com\/app\/uploads\/2024\/08\/LEaT-con_TT-Port-des-Lumieres_web.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes","Written by":"Lena"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/","url":"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/","name":"(AUSGEBUCHT) Port des Lumi\u00e8res | Immersive Kunstausstellung - LEaT","isPartOf":{"@id":"https:\/\/www.leatcon.com\/#website"},"datePublished":"2024-08-29T15:11:17+00:00","dateModified":"2024-10-21T19:44:36+00:00","breadcrumb":{"@id":"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.leatcon.com\/timetable\/event\/port-des-lumieres-immersive-kunstausstellung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.leatcon.com\/en\/leat-con-26\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/www.leatcon.com\/timetable\/event\/"},{"@type":"ListItem","position":3,"name":"(AUSGEBUCHT) Port des Lumi\u00e8res | Immersive Kunstausstellung"}]},{"@type":"WebSite","@id":"https:\/\/www.leatcon.com\/#website","url":"https:\/\/www.leatcon.com\/","name":"LEaT","description":"Live, Entertainment and Technology","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leatcon.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/mp-event\/17211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/mp-event"}],"about":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/types\/mp-event"}],"author":[{"embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/comments?post=17211"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/media\/17308"}],"wp:attachment":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/media?parent=17211"}],"wp:term":[{"taxonomy":"mp-event_category","embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/mp-event_category?post=17211"},{"taxonomy":"mp-event_tag","embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/mp-event_tag?post=17211"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/coauthors?post=17211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}