{"id":16110,"date":"2024-06-04T09:36:44","date_gmt":"2024-06-04T07:36:44","guid":{"rendered":"https:\/\/www.leatcon.com\/?post_type=mp-column&#038;p=16110"},"modified":"2024-09-25T15:47:16","modified_gmt":"2024-09-25T13:47:16","slug":"studiosofa-2","status":"publish","type":"mp-column","link":"https:\/\/www.leatcon.com\/en\/timetable\/column\/studiosofa-2\/","title":{"rendered":"Sound&#038;Recording Studiosofa"},"content":{"rendered":"","protected":false},"menu_order":0,"template":"","class_list":["post-16110","mp-column","type-mp-column","status-publish","hentry","mp-column-item"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.14 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sound&amp;Recording Studiosofa - LEaT<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sound&amp;Recording Studiosofa - LEaT\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/\" \/>\n<meta property=\"og:site_name\" content=\"LEaT\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-25T13:47:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marc Bohn\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/\",\"url\":\"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/\",\"name\":\"Sound&Recording Studiosofa - LEaT\",\"isPartOf\":{\"@id\":\"https:\/\/www.leatcon.com\/#website\"},\"datePublished\":\"2024-06-04T07:36:44+00:00\",\"dateModified\":\"2024-09-25T13:47:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.leatcon.com\/en\/leat-con-26\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Columns\",\"item\":\"https:\/\/www.leatcon.com\/timetable\/column\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sound&#038;Recording Studiosofa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.leatcon.com\/#website\",\"url\":\"https:\/\/www.leatcon.com\/\",\"name\":\"LEaT\",\"description\":\"Live, Entertainment and Technology\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.leatcon.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sound&Recording Studiosofa - LEaT","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/","og_locale":"en_US","og_type":"article","og_title":"Sound&Recording Studiosofa - LEaT","og_url":"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/","og_site_name":"LEaT","article_modified_time":"2024-09-25T13:47:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Marc Bohn"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/","url":"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/","name":"Sound&Recording Studiosofa - LEaT","isPartOf":{"@id":"https:\/\/www.leatcon.com\/#website"},"datePublished":"2024-06-04T07:36:44+00:00","dateModified":"2024-09-25T13:47:16+00:00","breadcrumb":{"@id":"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.leatcon.com\/timetable\/column\/studiosofa-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.leatcon.com\/en\/leat-con-26\/"},{"@type":"ListItem","position":2,"name":"Columns","item":"https:\/\/www.leatcon.com\/timetable\/column\/"},{"@type":"ListItem","position":3,"name":"Sound&#038;Recording Studiosofa"}]},{"@type":"WebSite","@id":"https:\/\/www.leatcon.com\/#website","url":"https:\/\/www.leatcon.com\/","name":"LEaT","description":"Live, Entertainment and Technology","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.leatcon.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/mp-column\/16110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/mp-column"}],"about":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/types\/mp-column"}],"wp:attachment":[{"href":"https:\/\/www.leatcon.com\/en\/wp-json\/wp\/v2\/media?parent=16110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}